{"id":2831,"date":"2024-08-13T13:00:43","date_gmt":"2024-08-13T13:00:43","guid":{"rendered":"https:\/\/mmevost.wpenginepowered.com\/success-stories\/benetalk-superpenguin-es\/"},"modified":"2025-11-25T14:23:01","modified_gmt":"2025-11-25T14:23:01","slug":"benetalk-superpenguin-es","status":"publish","type":"success-stories","link":"https:\/\/evolutioneurope.eu\/es\/casos-de-\u00e9xito\/benetalk-superpenguin-es\/","title":{"rendered":"BeneTalk \u2013 SuperPenguin"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p> SuperPenguin es una aplicaci\u00f3n que mejora la terapia del habla para ni\u00f1os con tartamudez. Recibi\u00f3 una subvenci\u00f3n de 1,7 millones de euros del NIHR.<\/p>\n","protected":false},"featured_media":2480,"template":"","meta":{"_acf_changed":false},"flags":[88],"program":[],"sector":[32,36],"class_list":["post-2831","success-stories","type-success-stories","status-publish","has-post-thumbnail","hentry","flags-uk","sector-digital-industria-y-espacio","sector-salud"],"acf":{"layouts_cases":[{"acf_fc_layout":"content","content":{"sections_settings":{"section_id":"","section_background":false,"section_padding":"base"},"content":"El tartamudeo es una condici\u00f3n neurol\u00f3gica que afecta el habla, causando la repetici\u00f3n de sonidos o bloqueos al hablar. Afecta al 5-8% de los ni\u00f1os, generando ansiedad y frustraci\u00f3n asociadas con dificultades en la escuela, las relaciones sociales, las oportunidades laborales y la salud mental a largo plazo.\r\n\r\nAunque se reconoce ampliamente que el apoyo temprano es fundamental, un tercio de los ni\u00f1os con tartamudez en el Reino Unido debe esperar al menos un a\u00f1o para recibir terapia.\r\n\r\nAqu\u00ed es donde entra en juego <a href=\"https:\/\/www.superpenguin.com\/\" target=\"_blank\" rel=\"noopener\">SuperPenguin<\/a>, una aplicaci\u00f3n m\u00f3vil y plataforma web dise\u00f1ada por <a href=\"https:\/\/www.benetalk.com\/\" target=\"_blank\" rel=\"noopener\">Benetalk<\/a> para padres y cuidadores de ni\u00f1os dentro del programa de terapia del habla del NHS. SuperPenguin se basa en dos aplicaciones anteriores desarrolladas para el tartamudeo y est\u00e1 dise\u00f1ada para potenciar el trabajo de los especialistas del NHS para familias con ni\u00f1os que tartamudean.\r\n\r\nLa <strong>subvenci\u00f3n de 1,7 millones de euros<\/strong> que ha recibido del Instituto Nacional para la Investigaci\u00f3n en Salud y Cuidado del Reino Unido (NIHR), a trav\u00e9s de los premios <a href=\"https:\/\/www.nihr.ac.uk\/explore-nihr\/funding-programmes\/invention-for-innovation.htm\" target=\"_blank\" rel=\"noopener\">i4i Product Development Awards<\/a>, permitir\u00e1 mejorar SuperPenguin para ofrecer nuevas ventajas, como atenci\u00f3n personalizada, accesibilidad remota, empoderamiento del paciente, toma de decisiones basada en datos, eficiencia de costos y escalabilidad para optimizar los recursos del NHS.\r\n\r\nAl mejorar la calidad y accesibilidad general de la atenci\u00f3n dentro de las v\u00edas existentes del NHS, la plataforma SuperPenguin representa un avance significativo en el campo de la terapia del habla.\r\n\r\n<a class=\"sk-btn\" href=\"https:\/\/evolutioneurope.eu\/es\/blog\/entrevista-sobre-innovacion-ceo-benetalk-nueva-aplicacion-de-logopedia-del-nhs\/\" target=\"_blank\" rel=\"noopener\">Lee la entrevista con el CEO de Benetalk<\/a>"}},{"acf_fc_layout":"media","media":{"sections_settings":{"section_id":"","section_background":false,"section_padding":"base"},"intro":"","section_type":"image","image":2478,"video_type":"mp4","upload_video":"","video_id":"","video_placeholder":"","video_title":"","button":null}}],"layouts":[{"acf_fc_layout":"quotes","quotes":{"quotes":[{"image":6479,"quote":"\"El papel de Evolution durante la solicitud de subvenci\u00f3n fue fundamental. El trabajo y el apoyo de Evolution Europe ha sido el mejor que he recibido hasta ahora. Recibimos apoyo en todas las fases del proceso, incluida la preparaci\u00f3n de la presentaci\u00f3n final.\"","image_mobile":6479,"author":"Jordi Fernandez, CEO & fundador de SuperPenguin, Benetalk","button":null}]}}]},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>BeneTalk \u2013 SuperPenguin - evolution-europe<\/title>\n<meta name=\"description\" content=\"SuperPenguin es una aplicaci\u00f3n que mejora la terapia del habla para ni\u00f1os con tartamudez. Recibi\u00f3 una subvenci\u00f3n de 1,7 millones de euros del NIHR.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/evolutioneurope.eu\/es\/casos-de-\u00e9xito\/benetalk-superpenguin-es\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BeneTalk \u2013 SuperPenguin\" \/>\n<meta property=\"og:description\" content=\"SuperPenguin es una aplicaci\u00f3n que mejora la terapia del habla para ni\u00f1os con tartamudez. Recibi\u00f3 una subvenci\u00f3n de 1,7 millones de euros del NIHR.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/evolutioneurope.eu\/es\/casos-de-\u00e9xito\/benetalk-superpenguin-es\/\" \/>\n<meta property=\"og:site_name\" content=\"evolution-europe\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-25T14:23:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/evolutioneurope.eu\/wp-content\/uploads\/2025\/10\/SuperPenguin-Banner-7-scaled.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1619\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/evolutioneurope.eu\\\/es\\\/casos-de-\u00e9xito\\\/benetalk-superpenguin-es\\\/\",\"url\":\"https:\\\/\\\/evolutioneurope.eu\\\/es\\\/casos-de-\u00e9xito\\\/benetalk-superpenguin-es\\\/\",\"name\":\"BeneTalk \u2013 SuperPenguin - evolution-europe\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/evolutioneurope.eu\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/evolutioneurope.eu\\\/es\\\/casos-de-\u00e9xito\\\/benetalk-superpenguin-es\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/evolutioneurope.eu\\\/es\\\/casos-de-\u00e9xito\\\/benetalk-superpenguin-es\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/evolutioneurope.eu\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/SuperPenguin-Banner-7-scaled.png\",\"datePublished\":\"2024-08-13T13:00:43+00:00\",\"dateModified\":\"2025-11-25T14:23:01+00:00\",\"description\":\"SuperPenguin es una aplicaci\u00f3n que mejora la terapia del habla para ni\u00f1os con tartamudez. Recibi\u00f3 una subvenci\u00f3n de 1,7 millones de euros del NIHR.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/evolutioneurope.eu\\\/es\\\/casos-de-\u00e9xito\\\/benetalk-superpenguin-es\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/evolutioneurope.eu\\\/es\\\/casos-de-\u00e9xito\\\/benetalk-superpenguin-es\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/evolutioneurope.eu\\\/es\\\/casos-de-\u00e9xito\\\/benetalk-superpenguin-es\\\/#primaryimage\",\"url\":\"https:\\\/\\\/evolutioneurope.eu\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/SuperPenguin-Banner-7-scaled.png\",\"contentUrl\":\"https:\\\/\\\/evolutioneurope.eu\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/SuperPenguin-Banner-7-scaled.png\",\"width\":2560,\"height\":1619},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/evolutioneurope.eu\\\/es\\\/casos-de-\u00e9xito\\\/benetalk-superpenguin-es\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/evolutioneurope.eu\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Success stories\",\"item\":\"https:\\\/\\\/evolutioneurope.eu\\\/es\\\/casos-de-\u00e9xito\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"BeneTalk \u2013 SuperPenguin\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/evolutioneurope.eu\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/evolutioneurope.eu\\\/es\\\/\",\"name\":\"evolution-europe\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/evolutioneurope.eu\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/evolutioneurope.eu\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/evolutioneurope.eu\\\/es\\\/#organization\",\"name\":\"Evolution Europe\",\"url\":\"https:\\\/\\\/evolutioneurope.eu\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/evolutioneurope.eu\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/evolutioneurope.eu\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/social-share-image-2000x1600-1.jpg\",\"contentUrl\":\"https:\\\/\\\/evolutioneurope.eu\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/social-share-image-2000x1600-1.jpg\",\"width\":2000,\"height\":1600,\"caption\":\"Evolution Europe\"},\"image\":{\"@id\":\"https:\\\/\\\/evolutioneurope.eu\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"BeneTalk \u2013 SuperPenguin - evolution-europe","description":"SuperPenguin es una aplicaci\u00f3n que mejora la terapia del habla para ni\u00f1os con tartamudez. Recibi\u00f3 una subvenci\u00f3n de 1,7 millones de euros del NIHR.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/evolutioneurope.eu\/es\/casos-de-\u00e9xito\/benetalk-superpenguin-es\/","og_locale":"es_ES","og_type":"article","og_title":"BeneTalk \u2013 SuperPenguin","og_description":"SuperPenguin es una aplicaci\u00f3n que mejora la terapia del habla para ni\u00f1os con tartamudez. Recibi\u00f3 una subvenci\u00f3n de 1,7 millones de euros del NIHR.","og_url":"https:\/\/evolutioneurope.eu\/es\/casos-de-\u00e9xito\/benetalk-superpenguin-es\/","og_site_name":"evolution-europe","article_modified_time":"2025-11-25T14:23:01+00:00","og_image":[{"width":2560,"height":1619,"url":"https:\/\/evolutioneurope.eu\/wp-content\/uploads\/2025\/10\/SuperPenguin-Banner-7-scaled.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/evolutioneurope.eu\/es\/casos-de-\u00e9xito\/benetalk-superpenguin-es\/","url":"https:\/\/evolutioneurope.eu\/es\/casos-de-\u00e9xito\/benetalk-superpenguin-es\/","name":"BeneTalk \u2013 SuperPenguin - evolution-europe","isPartOf":{"@id":"https:\/\/evolutioneurope.eu\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/evolutioneurope.eu\/es\/casos-de-\u00e9xito\/benetalk-superpenguin-es\/#primaryimage"},"image":{"@id":"https:\/\/evolutioneurope.eu\/es\/casos-de-\u00e9xito\/benetalk-superpenguin-es\/#primaryimage"},"thumbnailUrl":"https:\/\/evolutioneurope.eu\/wp-content\/uploads\/2025\/10\/SuperPenguin-Banner-7-scaled.png","datePublished":"2024-08-13T13:00:43+00:00","dateModified":"2025-11-25T14:23:01+00:00","description":"SuperPenguin es una aplicaci\u00f3n que mejora la terapia del habla para ni\u00f1os con tartamudez. Recibi\u00f3 una subvenci\u00f3n de 1,7 millones de euros del NIHR.","breadcrumb":{"@id":"https:\/\/evolutioneurope.eu\/es\/casos-de-\u00e9xito\/benetalk-superpenguin-es\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/evolutioneurope.eu\/es\/casos-de-\u00e9xito\/benetalk-superpenguin-es\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/evolutioneurope.eu\/es\/casos-de-\u00e9xito\/benetalk-superpenguin-es\/#primaryimage","url":"https:\/\/evolutioneurope.eu\/wp-content\/uploads\/2025\/10\/SuperPenguin-Banner-7-scaled.png","contentUrl":"https:\/\/evolutioneurope.eu\/wp-content\/uploads\/2025\/10\/SuperPenguin-Banner-7-scaled.png","width":2560,"height":1619},{"@type":"BreadcrumbList","@id":"https:\/\/evolutioneurope.eu\/es\/casos-de-\u00e9xito\/benetalk-superpenguin-es\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/evolutioneurope.eu\/es\/"},{"@type":"ListItem","position":2,"name":"Success stories","item":"https:\/\/evolutioneurope.eu\/es\/casos-de-\u00e9xito\/"},{"@type":"ListItem","position":3,"name":"BeneTalk \u2013 SuperPenguin"}]},{"@type":"WebSite","@id":"https:\/\/evolutioneurope.eu\/es\/#website","url":"https:\/\/evolutioneurope.eu\/es\/","name":"evolution-europe","description":"","publisher":{"@id":"https:\/\/evolutioneurope.eu\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/evolutioneurope.eu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/evolutioneurope.eu\/es\/#organization","name":"Evolution Europe","url":"https:\/\/evolutioneurope.eu\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/evolutioneurope.eu\/es\/#\/schema\/logo\/image\/","url":"https:\/\/evolutioneurope.eu\/wp-content\/uploads\/2026\/04\/social-share-image-2000x1600-1.jpg","contentUrl":"https:\/\/evolutioneurope.eu\/wp-content\/uploads\/2026\/04\/social-share-image-2000x1600-1.jpg","width":2000,"height":1600,"caption":"Evolution Europe"},"image":{"@id":"https:\/\/evolutioneurope.eu\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/evolutioneurope.eu\/es\/wp-json\/wp\/v2\/success-stories\/2831","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/evolutioneurope.eu\/es\/wp-json\/wp\/v2\/success-stories"}],"about":[{"href":"https:\/\/evolutioneurope.eu\/es\/wp-json\/wp\/v2\/types\/success-stories"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/evolutioneurope.eu\/es\/wp-json\/wp\/v2\/media\/2480"}],"wp:attachment":[{"href":"https:\/\/evolutioneurope.eu\/es\/wp-json\/wp\/v2\/media?parent=2831"}],"wp:term":[{"taxonomy":"flags","embeddable":true,"href":"https:\/\/evolutioneurope.eu\/es\/wp-json\/wp\/v2\/flags?post=2831"},{"taxonomy":"program","embeddable":true,"href":"https:\/\/evolutioneurope.eu\/es\/wp-json\/wp\/v2\/program?post=2831"},{"taxonomy":"sector","embeddable":true,"href":"https:\/\/evolutioneurope.eu\/es\/wp-json\/wp\/v2\/sector?post=2831"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}